{"id":5053,"date":"2018-01-24T14:16:04","date_gmt":"2018-01-24T13:16:04","guid":{"rendered":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/"},"modified":"2018-01-24T21:58:11","modified_gmt":"2018-01-24T20:58:11","slug":"hoy-es-24-2","status":"publish","type":"post","link":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/","title":{"rendered":"\u00a1Hoy es 24!"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Nuestro director da los buenos d\u00edas grupales a nuestros alumnos de Primaria en este mes tan especial.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-5054\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012-300x225.jpg\" alt=\"\" width=\"661\" height=\"496\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012-1080x810.jpg 1080w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012.jpg 1600w\" sizes=\"(max-width: 661px) 100vw, 661px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5051\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0000-300x225.jpg\" alt=\"\" width=\"667\" height=\"500\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0000-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0000-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0000.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0000-510x382.jpg 510w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestro director da los buenos d\u00edas grupales a nuestros alumnos de Primaria en este mes tan especial.<\/p>\n","protected":false},"author":3,"featured_media":5054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17,15],"tags":[],"class_list":["post-5053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio","category-portada-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Hoy es 24! - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Hoy es 24! - Colegio\" \/>\n<meta property=\"og:description\" content=\"Nuestro director da los buenos d\u00edas grupales a nuestros alumnos de Primaria en este mes tan especial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-24T13:16:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-24T20:58:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/761874a1b5fc292d8430c2be03bc4c30\"},\"headline\":\"\u00a1Hoy es 24!\",\"datePublished\":\"2018-01-24T13:16:04+00:00\",\"dateModified\":\"2018-01-24T20:58:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/\"},\"wordCount\":20,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/01\\\/IMG-20180124-WA0012.jpg\",\"articleSection\":[\"Colegio\",\"Portada noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/\",\"url\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/\",\"name\":\"\u00a1Hoy es 24! - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/01\\\/IMG-20180124-WA0012.jpg\",\"datePublished\":\"2018-01-24T13:16:04+00:00\",\"dateModified\":\"2018-01-24T20:58:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/761874a1b5fc292d8430c2be03bc4c30\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/01\\\/IMG-20180124-WA0012.jpg\",\"contentUrl\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/01\\\/IMG-20180124-WA0012.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/hoy-es-24-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Hoy es 24!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Linares\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/761874a1b5fc292d8430c2be03bc4c30\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Hoy es 24! - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Hoy es 24! - Colegio","og_description":"Nuestro director da los buenos d\u00edas grupales a nuestros alumnos de Primaria en este mes tan especial.","og_url":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/","og_site_name":"Colegio","article_published_time":"2018-01-24T13:16:04+00:00","article_modified_time":"2018-01-24T20:58:11+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012.jpg","type":"image\/jpeg"}],"author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/#article","isPartOf":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/"},"author":{"name":"Gestor Web","@id":"https:\/\/linares.salesianos.edu\/colegio\/#\/schema\/person\/761874a1b5fc292d8430c2be03bc4c30"},"headline":"\u00a1Hoy es 24!","datePublished":"2018-01-24T13:16:04+00:00","dateModified":"2018-01-24T20:58:11+00:00","mainEntityOfPage":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/"},"wordCount":20,"commentCount":0,"image":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/#primaryimage"},"thumbnailUrl":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012.jpg","articleSection":["Colegio","Portada noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/","url":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/","name":"\u00a1Hoy es 24! - Colegio","isPartOf":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/#primaryimage"},"image":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/#primaryimage"},"thumbnailUrl":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012.jpg","datePublished":"2018-01-24T13:16:04+00:00","dateModified":"2018-01-24T20:58:11+00:00","author":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/#\/schema\/person\/761874a1b5fc292d8430c2be03bc4c30"},"breadcrumb":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/#primaryimage","url":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012.jpg","contentUrl":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/01\/IMG-20180124-WA0012.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/linares.salesianos.edu\/colegio\/hoy-es-24-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/linares.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"\u00a1Hoy es 24!"}]},{"@type":"WebSite","@id":"https:\/\/linares.salesianos.edu\/colegio\/#website","url":"https:\/\/linares.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Linares","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linares.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/linares.salesianos.edu\/colegio\/#\/schema\/person\/761874a1b5fc292d8430c2be03bc4c30","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/5053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=5053"}],"version-history":[{"count":2,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/5053\/revisions"}],"predecessor-version":[{"id":5056,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/5053\/revisions\/5056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/5054"}],"wp:attachment":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=5053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=5053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=5053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}