{"id":5232,"date":"2018-02-14T16:45:12","date_gmt":"2018-02-14T15:45:12","guid":{"rendered":"https:\/\/linares.salesianos.edu\/colegio\/?p=5232"},"modified":"2018-02-14T16:45:12","modified_gmt":"2018-02-14T15:45:12","slug":"imposicion-de-ceniza-al-alumnado","status":"publish","type":"post","link":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/","title":{"rendered":"Imposici\u00f3n de ceniza al alumnado"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div dir=\"auto\">Ya ha empezado la Cuaresma. Convi\u00e9rtete y Cree en el Evangelio!!!<\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5233\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0011.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0011.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0011-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0011-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0011-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0011-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0011-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5234\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0012.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0012.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0012-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0012-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0012-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0012-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0012-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5236\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014-1.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014-1.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014-1-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014-1-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014-1-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014-1-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014-1-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5238\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0015.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0015.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0015-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0015-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0015-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0015-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0015-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5239\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0016.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0016.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0016-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0016-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0016-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0016-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0016-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ya ha empezado la Cuaresma. Convi\u00e9rtete y Cree en el Evangelio!!!<\/p>\n","protected":false},"author":3,"featured_media":5237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17],"tags":[],"class_list":["post-5232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imposici\u00f3n de ceniza al alumnado - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imposici\u00f3n de ceniza al alumnado - Colegio\" \/>\n<meta property=\"og:description\" content=\"Ya ha empezado la Cuaresma. Convi\u00e9rtete y Cree en el Evangelio!!!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-14T15:45:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/761874a1b5fc292d8430c2be03bc4c30\"},\"headline\":\"Imposici\u00f3n de ceniza al alumnado\",\"datePublished\":\"2018-02-14T15:45:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/\"},\"wordCount\":18,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/02\\\/IMG-20180214-WA0014.jpg\",\"articleSection\":[\"Colegio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/\",\"url\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/\",\"name\":\"Imposici\u00f3n de ceniza al alumnado - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/02\\\/IMG-20180214-WA0014.jpg\",\"datePublished\":\"2018-02-14T15:45:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/761874a1b5fc292d8430c2be03bc4c30\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/02\\\/IMG-20180214-WA0014.jpg\",\"contentUrl\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/02\\\/IMG-20180214-WA0014.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/imposicion-de-ceniza-al-alumnado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imposici\u00f3n de ceniza al alumnado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Linares\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/761874a1b5fc292d8430c2be03bc4c30\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imposici\u00f3n de ceniza al alumnado - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/","og_locale":"es_ES","og_type":"article","og_title":"Imposici\u00f3n de ceniza al alumnado - Colegio","og_description":"Ya ha empezado la Cuaresma. Convi\u00e9rtete y Cree en el Evangelio!!!","og_url":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/","og_site_name":"Colegio","article_published_time":"2018-02-14T15:45:12+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014.jpg","type":"image\/jpeg"}],"author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/#article","isPartOf":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/"},"author":{"name":"Gestor Web","@id":"https:\/\/linares.salesianos.edu\/colegio\/#\/schema\/person\/761874a1b5fc292d8430c2be03bc4c30"},"headline":"Imposici\u00f3n de ceniza al alumnado","datePublished":"2018-02-14T15:45:12+00:00","mainEntityOfPage":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/"},"wordCount":18,"commentCount":0,"image":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/#primaryimage"},"thumbnailUrl":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014.jpg","articleSection":["Colegio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/","url":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/","name":"Imposici\u00f3n de ceniza al alumnado - Colegio","isPartOf":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/#primaryimage"},"image":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/#primaryimage"},"thumbnailUrl":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014.jpg","datePublished":"2018-02-14T15:45:12+00:00","author":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/#\/schema\/person\/761874a1b5fc292d8430c2be03bc4c30"},"breadcrumb":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/#primaryimage","url":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014.jpg","contentUrl":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180214-WA0014.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/linares.salesianos.edu\/colegio\/imposicion-de-ceniza-al-alumnado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/linares.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Imposici\u00f3n de ceniza al alumnado"}]},{"@type":"WebSite","@id":"https:\/\/linares.salesianos.edu\/colegio\/#website","url":"https:\/\/linares.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Linares","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linares.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/linares.salesianos.edu\/colegio\/#\/schema\/person\/761874a1b5fc292d8430c2be03bc4c30","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/5232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=5232"}],"version-history":[{"count":1,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/5232\/revisions"}],"predecessor-version":[{"id":5240,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/5232\/revisions\/5240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/5237"}],"wp:attachment":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=5232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=5232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=5232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}