{"id":5273,"date":"2018-02-17T18:00:26","date_gmt":"2018-02-17T17:00:26","guid":{"rendered":"https:\/\/linares.salesianos.edu\/colegio\/?p=5273"},"modified":"2018-02-17T18:01:42","modified_gmt":"2018-02-17T17:01:42","slug":"se-abre-el-telon-del-cervantes","status":"publish","type":"post","link":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/","title":{"rendered":"\u00a1Se abre el tel\u00f3n del Cervantes!"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div dir=\"auto\">Salesianos Linares, comienza con \u00abLa chirigota m\u00e1s mona\u00bb, interpretada por los alumnos de 2EP.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5287\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0007.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0007.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0007-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0007-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0007-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0007-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0007-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5279\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0024.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0024.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0024-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0024-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0024-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0024-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0024-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/div>\n<div dir=\"auto\">\u00a1Los Ochenteros! Primer ciclo de la ESO!! Recordamos aquellos maravillosos a\u00f1os&#8230;<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5274\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5276\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0027.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0027.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0027-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0027-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0027-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0027-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0027-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/div>\n<div dir=\"auto\">\u00a1Unos payasos voluntariosos!<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5286\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0008.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0008.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0008-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0008-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0008-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0008-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0008-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5281\" src=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0019.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0019.jpg 1600w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0019-300x225.jpg 300w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0019-768x576.jpg 768w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0019-1024x768.jpg 1024w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0019-510x382.jpg 510w, https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0019-1080x810.jpg 1080w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Salesianos Linares, comienza con \u00abLa chirigota m\u00e1s mona\u00bb, interpretada por los alumnos de 2EP. \u00a1Los Ochenteros! Primer ciclo de la ESO!! Recordamos aquellos maravillosos a\u00f1os&#8230; \u00a1Unos payasos voluntariosos!<\/p>\n","protected":false},"author":3,"featured_media":5274,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17,15],"tags":[],"class_list":["post-5273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio","category-portada-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Se abre el tel\u00f3n del Cervantes! - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Se abre el tel\u00f3n del Cervantes! - Colegio\" \/>\n<meta property=\"og:description\" content=\"Salesianos Linares, comienza con \u00abLa chirigota m\u00e1s mona\u00bb, interpretada por los alumnos de 2EP. \u00a1Los Ochenteros! Primer ciclo de la ESO!! Recordamos aquellos maravillosos a\u00f1os&#8230; \u00a1Unos payasos voluntariosos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-17T17:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-17T17:01:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/761874a1b5fc292d8430c2be03bc4c30\"},\"headline\":\"\u00a1Se abre el tel\u00f3n del Cervantes!\",\"datePublished\":\"2018-02-17T17:00:26+00:00\",\"dateModified\":\"2018-02-17T17:01:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/\"},\"wordCount\":37,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/02\\\/IMG-20180217-WA0031.jpg\",\"articleSection\":[\"Colegio\",\"Portada noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/\",\"url\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/\",\"name\":\"\u00a1Se abre el tel\u00f3n del Cervantes! - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/02\\\/IMG-20180217-WA0031.jpg\",\"datePublished\":\"2018-02-17T17:00:26+00:00\",\"dateModified\":\"2018-02-17T17:01:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/761874a1b5fc292d8430c2be03bc4c30\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/02\\\/IMG-20180217-WA0031.jpg\",\"contentUrl\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2018\\\/02\\\/IMG-20180217-WA0031.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/se-abre-el-telon-del-cervantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Se abre el tel\u00f3n del Cervantes!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Linares\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/linares.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/761874a1b5fc292d8430c2be03bc4c30\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Se abre el tel\u00f3n del Cervantes! - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Se abre el tel\u00f3n del Cervantes! - Colegio","og_description":"Salesianos Linares, comienza con \u00abLa chirigota m\u00e1s mona\u00bb, interpretada por los alumnos de 2EP. \u00a1Los Ochenteros! Primer ciclo de la ESO!! Recordamos aquellos maravillosos a\u00f1os&#8230; \u00a1Unos payasos voluntariosos!","og_url":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/","og_site_name":"Colegio","article_published_time":"2018-02-17T17:00:26+00:00","article_modified_time":"2018-02-17T17:01:42+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031.jpg","type":"image\/jpeg"}],"author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/#article","isPartOf":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/"},"author":{"name":"Gestor Web","@id":"https:\/\/linares.salesianos.edu\/colegio\/#\/schema\/person\/761874a1b5fc292d8430c2be03bc4c30"},"headline":"\u00a1Se abre el tel\u00f3n del Cervantes!","datePublished":"2018-02-17T17:00:26+00:00","dateModified":"2018-02-17T17:01:42+00:00","mainEntityOfPage":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/"},"wordCount":37,"commentCount":0,"image":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/#primaryimage"},"thumbnailUrl":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031.jpg","articleSection":["Colegio","Portada noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/","url":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/","name":"\u00a1Se abre el tel\u00f3n del Cervantes! - Colegio","isPartOf":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/#primaryimage"},"image":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/#primaryimage"},"thumbnailUrl":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031.jpg","datePublished":"2018-02-17T17:00:26+00:00","dateModified":"2018-02-17T17:01:42+00:00","author":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/#\/schema\/person\/761874a1b5fc292d8430c2be03bc4c30"},"breadcrumb":{"@id":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/#primaryimage","url":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031.jpg","contentUrl":"https:\/\/linares.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/16\/2018\/02\/IMG-20180217-WA0031.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/linares.salesianos.edu\/colegio\/se-abre-el-telon-del-cervantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/linares.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"\u00a1Se abre el tel\u00f3n del Cervantes!"}]},{"@type":"WebSite","@id":"https:\/\/linares.salesianos.edu\/colegio\/#website","url":"https:\/\/linares.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Linares","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linares.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/linares.salesianos.edu\/colegio\/#\/schema\/person\/761874a1b5fc292d8430c2be03bc4c30","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b73ca4bac25ce7754f7f4385e9e2fa5555a4790c6e3856e5a7fd8fac2e605e64?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/5273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=5273"}],"version-history":[{"count":2,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/5273\/revisions"}],"predecessor-version":[{"id":5289,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/5273\/revisions\/5289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/5274"}],"wp:attachment":[{"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=5273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=5273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linares.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=5273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}